{"id":4708,"date":"2023-06-19T11:27:13","date_gmt":"2023-06-19T15:27:13","guid":{"rendered":"http:\/\/colegiosantacecilia.cl\/new\/?p=4708"},"modified":"2023-06-23T17:33:20","modified_gmt":"2023-06-23T21:33:20","slug":"convenio-dental","status":"publish","type":"post","link":"http:\/\/colegiosantacecilia.cl\/new\/convenio-dental\/","title":{"rendered":"Convenio Dental"},"content":{"rendered":"<p>Presentamos a la Familia Ceciliana un convenio Dental con<strong> Cl\u00ednica Harmony.<\/strong> Este beneficio para las familias de nuestro colegio surge de la iniciativa de una Ex Estudiante Ceciliana, Cirujana Dentista y due\u00f1a Cl\u00ednica Harmony, ubicada en Av. Libertador Bernardo O`Higgins 4050, Of. 1212, Estaci\u00f3n Central (Metro San Alberto Hurtado).<\/p>\n<p><strong>Beneficios:<\/strong><\/p>\n<ul>\n<li>Valores preferenciales (<a href=\"http:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2023\/06\/Arancel-Preferente-2023-.pdf\">ver tabla de precios<\/a>)<\/li>\n<\/ul>\n<p><strong>Beneficiarios:<\/strong><\/p>\n<ul>\n<li>Estudiantes<\/li>\n<li>Funcionarios<\/li>\n<li>Apoderados<\/li>\n<\/ul>\n<p>Para acceder al beneficio solo debe demostrar la pertenencia a la organizaci\u00f3n a trav\u00e9s de alg\u00fan documento institucional: certificado de notas o de alumna regular (en el caso de estudiantes y apoderados), liquidaciones de sueldo, certificado de antig\u00fcedad, o de AFP (en el caso de funcionarios).<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2023\/06\/Flyer-1.jpg\" alt=\"\" width=\"500\" height=\"777\" class=\"aligncenter wp-image-4711\" srcset=\"http:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2023\/06\/Flyer-1.jpg 354w, http:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2023\/06\/Flyer-1-193x300.jpg 193w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentamos a la Familia Ceciliana un convenio Dental con Cl\u00ednica Harmony. Este beneficio para las familias de nuestro colegio surge de la iniciativa de una Ex Estudiante Ceciliana, Cirujana Dentista y due\u00f1a Cl\u00ednica Harmony, ubicada en Av. Libertador Bernardo O`Higgins 4050, Of. 1212, Estaci\u00f3n Central (Metro San Alberto Hurtado). Beneficios: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-4708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beneficios"],"views":899,"_links":{"self":[{"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/4708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/comments?post=4708"}],"version-history":[{"count":2,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/4708\/revisions"}],"predecessor-version":[{"id":4725,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/4708\/revisions\/4725"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media\/4712"}],"wp:attachment":[{"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media?parent=4708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/categories?post=4708"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/tags?post=4708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}