{"id":249,"date":"2013-03-13T13:56:13","date_gmt":"2013-03-13T17:56:13","guid":{"rendered":"http:\/\/colegiosantacecilia.cl\/new\/pastoral\/"},"modified":"2024-03-16T16:29:21","modified_gmt":"2024-03-16T20:29:21","slug":"pastoral","status":"publish","type":"page","link":"https:\/\/colegiosantacecilia.cl\/new\/pastoral\/","title":{"rendered":"Pastoral"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"249\" class=\"elementor elementor-249\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d524a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d524a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5683f9d\" data-id=\"5683f9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9372095 elementor-widget elementor-widget-image-gallery\" data-id=\"9372095\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-249 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"48253334111_64da9a48de_h\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODc3LCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wOFwvNDgyNTMzMzQxMTFfNjRkYTlhNDhkZV9oLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/48253334111_64da9a48de_h.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/48253334111_64da9a48de_h-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"48128165596_28a04b2473_b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODczLCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wOFwvNDgxMjgxNjU1OTZfMjhhMDRiMjQ3M19iLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/48128165596_28a04b2473_b.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/48128165596_28a04b2473_b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"46993557905_b67c2bfc1c_h\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODYwLCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wNVwvNDY5OTM1NTc5MDVfYjY3YzJiZmMxY19oLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/05\/46993557905_b67c2bfc1c_h.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/05\/46993557905_b67c2bfc1c_h-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"40851541423_1a7b646f08_k\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODUxLCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wNVwvNDA4NTE1NDE0MjNfMWE3YjY0NmYwOF9rLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/05\/40851541423_1a7b646f08_k.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/05\/40851541423_1a7b646f08_k-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"48126600331_42a8ab132d_k\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODI4LCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wN1wvNDgxMjY2MDAzMzFfNDJhOGFiMTMyZF9rLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/07\/48126600331_42a8ab132d_k.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/07\/48126600331_42a8ab132d_k-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"12_actonavidad_1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzk4LCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wNlwvMTJfYWN0b25hdmlkYWRfMS5qcGciLCJzbGlkZXNob3ciOiI5MzcyMDk1In0%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/12_actonavidad_1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/12_actonavidad_1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"11_confi_3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzk0LCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wNlwvMTFfY29uZmlfMy5qcGciLCJzbGlkZXNob3ciOiI5MzcyMDk1In0%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/11_confi_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/11_confi_3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9372095\" data-elementor-lightbox-title=\"10_comuniones_3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzkwLCJ1cmwiOiJodHRwczpcL1wvY29sZWdpb3NhbnRhY2VjaWxpYS5jbFwvbmV3XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wNlwvMTBfY29tdW5pb25lc18zLmpwZyIsInNsaWRlc2hvdyI6IjkzNzIwOTUifQ%3D%3D\" href='https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/10_comuniones_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/06\/10_comuniones_3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e53b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58e53b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65beec6\" data-id=\"65beec6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-557ae4d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"557ae4d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d01cf1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d01cf1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f943f97\" data-id=\"f943f97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-058d21a elementor-widget elementor-widget-image\" data-id=\"058d21a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"749\" src=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/Logos-y-timbres-14.jpg\" class=\"attachment-large size-large wp-image-994\" alt=\"\" srcset=\"https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/Logos-y-timbres-14.jpg 887w, https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/Logos-y-timbres-14-150x150.jpg 150w, https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/Logos-y-timbres-14-300x300.jpg 300w, https:\/\/colegiosantacecilia.cl\/new\/wp-content\/uploads\/2019\/08\/Logos-y-timbres-14-768x767.jpg 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-fcc7b78\" data-id=\"fcc7b78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db21cc4 elementor-widget elementor-widget-text-editor\" data-id=\"db21cc4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14pt;\">La Pastoral del Colegio Santa Cecilia tiene como finalidad dar a conocer la Buena Noticia del Evangelio por medio de la formaci\u00f3n cristiana, ayudando a cada alumna, apoderado y funcionario del establecimiento en el crecimiento de la fe que debe estar impregnada de la Espiritualidad de la Sangre de Cristo centrada en las cuatro dimensiones de la Iglesia: Prof\u00e9tica, Lit\u00fagica, Comunitaria y Servicio.<\/span><\/p><ul><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e8a5a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e8a5a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb21e6a\" data-id=\"fb21e6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efafc25 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"efafc25\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Pastoral del Colegio Santa Cecilia tiene como finalidad dar a conocer la Buena Noticia del Evangelio por medio de la formaci\u00f3n cristiana, ayudando a cada alumna, apoderado y funcionario del establecimiento en el crecimiento de la fe que debe estar impregnada de la Espiritualidad de la Sangre de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":734,"parent":0,"menu_order":17,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-249","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/pages\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":21,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/pages\/249\/revisions"}],"predecessor-version":[{"id":5291,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/pages\/249\/revisions\/5291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media\/734"}],"wp:attachment":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media?parent=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}