{"id":3627,"date":"2022-04-19T00:55:05","date_gmt":"2022-04-19T04:55:05","guid":{"rendered":"http:\/\/colegiosantacecilia.cl\/new\/?p=3627"},"modified":"2022-04-22T01:10:47","modified_gmt":"2022-04-22T05:10:47","slug":"reunion-con-estudiantes-nuevas","status":"publish","type":"post","link":"https:\/\/colegiosantacecilia.cl\/new\/reunion-con-estudiantes-nuevas\/","title":{"rendered":"Reuni\u00f3n con estudiantes nuevas"},"content":{"rendered":"<p>El lunes 18 de abril, despu\u00e9s de la formaci\u00f3n se realiz\u00f3 un encuentro entre Direcci\u00f3n, Coordinaci\u00f3n acad\u00e9mica y las estudiantes que se integraron a partir de este a\u00f1o a nuestro colegio en todos los niveles.<\/p>\n<p>La instancia buscaba generar un espacio de conversaci\u00f3n y compartir en torno a la experiencia de ser nuevas en la comunidad Ceciliana. La conversaci\u00f3n fue guiada por la Hna. Anabella Parra Mu\u00f1oz (Directora), Daniela Donoso (Coordinadora Academ\u00edca), Macarena Morales y Mar\u00eda Jes\u00fas Cuevas (Coordinadoras de ciclo).<\/p>\n<p>Agradecemos la confianza de todas las estudiantes en compartir sus vivencias y la disposici\u00f3n para escuchar y aprender de sus pares.<\/p>\n<p>A los apoderados de ellas, los dejamos invitados a participar de la <a href=\"http:\/\/colegiosantacecilia.cl\/new\/invitacion-reunion-bienvenida-apoderados-nuevos\/\">Reuni\u00f3n de bienvenida para apoderados nuevos 2022<\/a> que se realizar\u00e1 el pr\u00f3ximo 27 de abril a las 18:00 horas en nuestro colegio.<\/p>\n<p>Fotos de la actividad:<\/p>\n<p><a data-flickr-embed=\"true\" data-header=\"true\" href=\"https:\/\/www.flickr.com\/photos\/colegiosantacecilia\/albums\/72177720298298683\" title=\"Reuni\u00f3n con estudiantes nuevas\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/52021447690_d99f66048a_c.jpg\" width=\"800\" height=\"600\" alt=\"Reuni\u00f3n con estudiantes nuevas\" \/><\/a><script async src=\"\/\/embedr.flickr.com\/assets\/client-code.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 18 de abril, despu\u00e9s de la formaci\u00f3n se realiz\u00f3 un encuentro entre Direcci\u00f3n, Coordinaci\u00f3n acad\u00e9mica y las estudiantes que se integraron a partir de este a\u00f1o a nuestro colegio en todos los niveles. La instancia buscaba generar un espacio de conversaci\u00f3n y compartir en torno a la experiencia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"views":956,"_links":{"self":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/3627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/comments?post=3627"}],"version-history":[{"count":1,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/3627\/revisions"}],"predecessor-version":[{"id":3629,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/3627\/revisions\/3629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media\/3628"}],"wp:attachment":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media?parent=3627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/categories?post=3627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/tags?post=3627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}