{"id":6879,"date":"2026-07-15T12:28:21","date_gmt":"2026-07-15T16:28:21","guid":{"rendered":"https:\/\/colegiosantacecilia.cl\/new\/?p=6879"},"modified":"2026-07-15T12:40:07","modified_gmt":"2026-07-15T16:40:07","slug":"comunicado-suspension-de-clases-viernes-17-de-julio","status":"publish","type":"post","link":"https:\/\/colegiosantacecilia.cl\/new\/comunicado-suspension-de-clases-viernes-17-de-julio\/","title":{"rendered":"Comunicado Suspensi\u00f3n de clases viernes 17 de julio"},"content":{"rendered":"<p>Estimadas Familias del Colegio Santa Cecilia:<\/p>\n<p><span>Atendiendo la determinaci\u00f3n de las autoridades y la alarma meteorol\u00f3gica emitida por la Direcci\u00f3n Meteorol\u00f3gica de Chile para la Regi\u00f3n Metropolitana, vigente desde este jueves hasta el domingo, y con el prop\u00f3sito de resguardar la seguridad y el bienestar de toda nuestra Comunidad Educativa, recordamos a ustedes que las clases del\u00a0<\/span><strong>viernes 17 de julio de 2026 se encuentran suspendidas.<span>\u00a0<\/span><\/strong><span>Por lo que,\u00a0<b>el colegio permanecer\u00e1 cerrado sin atenci\u00f3n de estudiantes ni actividades administrativas.<\/b><\/span><\/p>\n<p>Les recuerdo el llamado de las autoridades de permanecer en casa en los casos que sea posible y seguir las recomendaciones de prevenci\u00f3n y autocuidado. Adem\u00e1s de mantenerse informados por medios oficiales respecto a la evoluci\u00f3n del sistema frontal.<\/p>\n<p>El Colegio retomar\u00e1 su jornada habitual a partir del lunes 20 de julio.<\/p>\n<p>Agradecida de cada familia por su comprensi\u00f3n y confiada en que Mar\u00eda, Nuestra Se\u00f1ora de la Preciosa Sangre, nos acompa\u00f1e y proteja, me despido afectuosamente.<\/p>\n<p>Atentamente,<\/p>\n<p>Hna. Gabriela Contreras Rosas<br \/>\nDirectora del Colegio Santa Cecilia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas Familias del Colegio Santa Cecilia: Atendiendo la determinaci\u00f3n de las autoridades y la alarma meteorol\u00f3gica emitida por la Direcci\u00f3n Meteorol\u00f3gica de Chile para la Regi\u00f3n Metropolitana, vigente desde este jueves hasta el domingo, y con el prop\u00f3sito de resguardar la seguridad y el bienestar de toda nuestra Comunidad Educativa, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,3],"tags":[],"class_list":["post-6879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informaciones","category-noticias"],"views":69,"_links":{"self":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/6879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/comments?post=6879"}],"version-history":[{"count":2,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/6879\/revisions"}],"predecessor-version":[{"id":6881,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/posts\/6879\/revisions\/6881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media\/6353"}],"wp:attachment":[{"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/media?parent=6879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/categories?post=6879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegiosantacecilia.cl\/new\/wp-json\/wp\/v2\/tags?post=6879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}